{"id":6268,"date":"2023-06-15T20:40:05","date_gmt":"2023-06-15T23:40:05","guid":{"rendered":"http:\/\/patrimonio.art.br\/opocedoc\/?post_type=tnc_col_3853_item&#038;p=6268"},"modified":"2023-11-16T08:43:56","modified_gmt":"2023-11-16T11:43:56","slug":"os-arana-e-sua-indianidade-disputas-internas-por-legitimidade-e-o-reconhecimento-oficial-como-grupo-indigena","status":"publish","type":"tnc_col_3853_item","link":"https:\/\/patrimonio.art.br\/opocedoc\/teses-dissertacoes-e-outros-trabalhos-monograficos\/os-arana-e-sua-indianidade-disputas-internas-por-legitimidade-e-o-reconhecimento-oficial-como-grupo-indigena\/","title":{"rendered":"Os Aran\u00e3 e sua indianidade: disputas internas por legitimidade e o reconhecimento oficial como grupo ind\u00edgena"},"content":{"rendered":"<p>Este trabalho se debru\u00e7a sobre o processo de constru\u00e7\u00e3o da identidade \u00e9tnica do grupo ind\u00edgena Aran\u00e3. A disserta\u00e7\u00e3o investiga como o grupo, ao se relacionar com diferentes agentes externos, construiu uma concep\u00e7\u00e3o pr\u00f3pria da sua indianidade Aran\u00e3, utilizando, entretanto, informa\u00e7\u00f5es e dados que eram desconhecidos anteriormente. Um dos pontos centrais desse trabalho \u00e9 argumentar que a utiliza\u00e7\u00e3o de dados e informa\u00e7\u00f5es externos, anteriormente desconhecidos pelo grupo, n\u00e3o invalida nem sua etnicidade sem seu processo de recupera\u00e7\u00e3o de suas tradi\u00e7\u00f5es e de sua etnohist\u00f3ria. No caso Aran\u00e3, a comunidade sempre afirmava que era descendente de ind\u00edgenas da regi\u00e3o, que seus antepassados foram pegos no la\u00e7o. Entretanto, eles desconheciam o no-me de seu grupo \u00e9tnico. Foi buscando na historiografia ocidental que o grupo conseguiu (re)descobrir seu nome ind\u00edgena. Dois grupos familiares distintos compunham os Aran\u00e3: a fam\u00edlia Caboclo e a fam\u00edlia \u00cdndio. O trabalho investiga como se deu essa coopera\u00e7\u00e3o entre as diferentes fam\u00edlias e quais caracter\u00edsticas comuns levaram a constru\u00e7\u00e3o de uma identidade coletiva. Por\u00e9m, as rela\u00e7\u00f5es entre os dois grupos familiares acabaram tornando-se tensas o suficiente para provocar uma divis\u00e3o interna. A disserta\u00e7\u00e3o usa tanto entrevistas com documentos produzidos pelos Aran\u00e3 para investigar como aconteceu a uni\u00e3o entre as fam\u00edlias, o desentendimento e, posteriormente, a divis\u00e3o do grupo. Ao analisar as entrevistas e os documentos, pode-se perceber que existem v\u00e1rias quest\u00f5es por detr\u00e1s daquilo que \u00e9 explicitado. O trabalho utiliza teorias e metodologias sobre etnicidade e identidade para melhor abordar a o caso Aran\u00e3 e acaba por fazer algumas sugest\u00f5es sobre como abordar casos semelhantes de constru\u00e7\u00e3o de uma identidade \u00e9tnica.<\/p>\n","protected":false},"featured_media":5007,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","blocksy_meta":"","_links":{"self":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/6268"}],"collection":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item"}],"about":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/types\/tnc_col_3853_item"}],"replies":[{"embeddable":true,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/comments?post=6268"}],"version-history":[{"count":1,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/6268\/revisions"}],"predecessor-version":[{"id":6304,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/6268\/revisions\/6304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/media\/5007"}],"wp:attachment":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/media?parent=6268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}