{"id":5798,"date":"2023-06-13T18:12:41","date_gmt":"2023-06-13T21:12:41","guid":{"rendered":"http:\/\/patrimonio.art.br\/opocedoc\/?post_type=tnc_col_3853_item&#038;p=5798"},"modified":"2023-11-16T08:43:57","modified_gmt":"2023-11-16T11:43:57","slug":"a-retomada-tupinamba-no-tribunal-de-justica-controversias-sociotecnicas-e-conflitos-ontologicos-na-demarcacao-da-terra-indigena-tupinamba-de-olivenca","status":"publish","type":"tnc_col_3853_item","link":"https:\/\/patrimonio.art.br\/opocedoc\/teses-dissertacoes-e-outros-trabalhos-monograficos\/a-retomada-tupinamba-no-tribunal-de-justica-controversias-sociotecnicas-e-conflitos-ontologicos-na-demarcacao-da-terra-indigena-tupinamba-de-olivenca\/","title":{"rendered":"A retomada Tupinamb\u00e1 no tribunal de justi\u00e7a : controv\u00e9rsias sociot\u00e9cnicas e conflitos ontol\u00f3gicos na demarca\u00e7\u00e3o da Terra Ind\u00edgena Tupinamb\u00e1 de Oliven\u00e7a"},"content":{"rendered":"<p>Este trabalho versa sobre a controv\u00e9rsia gerada em torno da demarca\u00e7\u00e3o da Terra Ind\u00edgena Tupinamb\u00e1 de Oliven\u00e7a e de sua consequente judicializa\u00e7\u00e3o. A fim de seguir a controv\u00e9rsia, acompanho os autos de um processo judicial, acrescentando outros documentos, textos e sujeitos que me foram sendo apontados atrav\u00e9s deles. O objetivo que busquei alcan\u00e7ar foi identificar e discutir os principais argumentos acionados por n\u00e3o ind\u00edgenas a fim de impedir o reconhecimento do direito dos \u00edndios \u00e0s suas terras tradicionais e, por outro lado, compreender as pr\u00e1ticas de resist\u00eancia e territorializa\u00e7\u00e3o ind\u00edgena diante desse cen\u00e1rio de confronto e confinamento ao longo de 500 anos. Outra quest\u00e3o pertinente a esta disserta\u00e7\u00e3o \u00e9 compreender os efeitos da fric\u00e7\u00e3o\/atrito que se desenvolvem na disputa territorial entre povos que operam segundo premissas ontol\u00f3gicas diversas e a maneira como essas ontologias s\u00e3o ou n\u00e3o acolhidas no \u00e2mbito legislativo e da adjudica\u00e7\u00e3o. Ao longo da disserta\u00e7\u00e3o, apresento resumidamente a hist\u00f3ria da legisla\u00e7\u00e3o indigenista o Brasil, da ocupa\u00e7\u00e3o do territ\u00f3rio onde vivem os Tupinamb\u00e1 de Oliven\u00e7a desde o s\u00e9culo XVI e dos atritos\/fric\u00e7\u00f5es entre os Tupinamb\u00e1 e os colonizadores\/usurpadores de suas terras at\u00e9 o final do s\u00e9culo XX, quando os Tupinamb\u00e1 finalmente conseguem ser oficialmente reconhecidos pelo Estado como um povo ind\u00edgena com legitimidade para reivindicar seu territ\u00f3rio. Deste modo, mostro a maneira como o territ\u00f3rio Tupinamb\u00e1 vai se delineando sob a forma de Terra Ind\u00edgena Tupinamb\u00e1 de Oliven\u00e7a. Apresento tamb\u00e9m os principais atores que movem esta controv\u00e9rsia e seus respectivos enquadramentos conceituais acerca da terra e das quest\u00f5es identit\u00e1rias, trazendo \u00e0 baila os problemas que movem o processo judicial deflagrado pela impetra\u00e7\u00e3o do Mandado de Seguran\u00e7a, a saber: quem \u00e9 \u00edndio, quem n\u00e3o \u00e9? Quando se deixa de ser \u00edndio? Quais s\u00e3o as condi\u00e7\u00f5es jur\u00eddicas necess\u00e1rias para se ter acesso \u00e0 terra? \u00c9 poss\u00edvel que entidades espirituais sejam sujeitos de direito? Quem \u00e9 parte leg\u00edtima para dizer quem pode e quem n\u00e3o pode habitar um territ\u00f3rio? Concluo esta disserta\u00e7\u00e3o com uma reflex\u00e3o acerca da resist\u00eancia ind\u00edgena, suas estrat\u00e9gias e alian\u00e7as diante das investidas coloniais e dos interesses capitalistas e os respectivos desafios que essa resist\u00eancia coloca ao Estado e ao Poder Judici\u00e1rio.<\/p>\n","protected":false},"featured_media":5007,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","blocksy_meta":"","_links":{"self":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/5798"}],"collection":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item"}],"about":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/types\/tnc_col_3853_item"}],"replies":[{"embeddable":true,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/comments?post=5798"}],"version-history":[{"count":1,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/5798\/revisions"}],"predecessor-version":[{"id":5833,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/tnc_col_3853_item\/5798\/revisions\/5833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/media\/5007"}],"wp:attachment":[{"href":"https:\/\/patrimonio.art.br\/opocedoc\/wp-json\/wp\/v2\/media?parent=5798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}